{"id":6175,"date":"2022-09-09T09:15:53","date_gmt":"2022-09-09T07:15:53","guid":{"rendered":"https:\/\/bktkancelaria.pl\/?p=6175"},"modified":"2022-09-02T16:31:37","modified_gmt":"2022-09-02T14:31:37","slug":"umowy-szkoleniowe-a-delegowanie","status":"publish","type":"post","link":"https:\/\/bktkancelaria.pl\/de\/ausbildungsvertrage-und-entsendung\/","title":{"rendered":"Ausbildungsvertr\u00e4ge und Abordnungen - eine M\u00f6glichkeit, die Vorschriften zu umgehen?"},"content":{"rendered":"<p style=\"text-align: justify;\"><span data-contrast=\"none\">Polen ist der unangefochtene Spitzenreiter in Bezug auf<\/span><span data-contrast=\"none\"> Erbringung von grenz\u00fcberschreitenden Dienstleistungen. Nach den Daten der Europ\u00e4ischen Kommission, die im Vorschlag f\u00fcr die Umsetzungsrichtlinie vorgelegt wurden, gibt es in der Europ\u00e4ischen Union etwa 1 Million entsandte Arbeitnehmer, davon 23% Polen. In weiteren Orten<\/span><span data-contrast=\"none\">an zweiter und dritter Stelle, mit einer viel geringeren Zahl, d.h. etwa 200.000 Besch\u00e4ftigten<\/span><span data-contrast=\"none\">\u0105<\/span><span data-contrast=\"none\"> Frankreich und Deutschland. Das Ph\u00e4nomen der Entsendung ist f\u00fcr die polnische Wirtschaft von gro\u00dfer Bedeutung. Sie stellt einen der Wettbewerbsvorteile auf dem Binnenmarkt der Europ\u00e4ischen Union dar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\"> Infolgedessen suchen Arbeitgeber zunehmend nach M\u00f6glichkeiten, ihre Mitarbeiter zu geringen Kosten in andere EU-L\u00e4nder zu entsenden. <strong>Wir stellen fest, dass sich Ausbildungsvertr\u00e4ge als eine M\u00f6glichkeit, leichter zu delegieren, als recht verbreitet erweisen<\/strong>. Aber ist dies wirklich ein wirksamer Weg, um sich von allen Folgen der Entsendung Ihrer Mitarbeiter ins Ausland zu befreien?<\/span><\/p>\n<p style=\"text-align: justify;\">Wir antworten im Folgenden.<\/p>\n<p style=\"text-align: justify;\">Lesen Sie auch: <strong><a href=\"https:\/\/bktkancelaria.pl\/de\/delegowanie-pracownikow-za-granice-w-2022\/\">Entsendung von Arbeitnehmern ins Ausland im Jahr 2022 und die Situation der Ukrainer<\/a><\/strong><\/p>\n<h2 style=\"text-align: left;\"><strong>Wie sieht der Prozess der Entsendung eines Mitarbeiters aus?\u00a0<\/strong><\/h2>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Es lohnt sich, zu Beginn kurz zu erkl\u00e4ren, was die Entsendung von Arbeitnehmern ist. Die Entsendung eines Arbeitnehmers in ein anderes Land innerhalb der Europ\u00e4ischen Union ist nichts anderes als<\/span><span data-contrast=\"none\"> Bereitstellung durch <\/span><span data-contrast=\"none\">Dienstleistungserbringer in einem anderen Mitgliedstaat. In diesem Fall muss der Dienstleister in der Lage sein, seinen Arbeitnehmer in ein anderes Land zu entsenden, um den Auftrag zu erf\u00fcllen. Das Verfahren der Entsendung von Arbeitnehmern beruht auf der sogenannten innergemeinschaftlichen Dienstleistungsfreiheit der Europ\u00e4ischen Union. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: left;\">Ausbildungsvertr\u00e4ge und Entsendung - EU-Verordnungen<\/h2>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Der Prozess der Entsendung von Arbeitnehmern wird durch die Rechtsvorschriften der Europ\u00e4ischen Union und insbesondere durch die Richtlinien 96\/71\/EG, 2014\/67\/EU und 2018\/957 geregelt:  96\/71\/EG, 2014\/67\/EU und 2018\/957. Diese Bestimmungen zielen darauf ab, den Schutz der Arbeitnehmer w\u00e4hrend der Entsendung zu gew\u00e4hrleisten - in Verbindung mit der Freiheit, grenz\u00fcberschreitende Dienstleistungen zu erbringen. Durch die Festlegung verbindlicher Vorschriften, die (grunds\u00e4tzlich) eingehalten werden sollten, sollen angemessene Arbeitsbedingungen sowie der Schutz von Gesundheit und Sicherheit der entsandten Arbeitnehmer gew\u00e4hrleistet werden. <\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Wir haben in unserem Blog bereits mehrfach ausf\u00fchrlicher \u00fcber die Delegation geschrieben. Sowohl im Zusammenhang mit der Delegation an sich als auch mit der Delegation von bestimmten Berufsgruppen. Wenn Sie an diesem Thema interessiert sind, lesen Sie auch: <strong><a href=\"https:\/\/bktkancelaria.pl\/de\/entsendung-von-pflegekraften-aus-drittstaaten-nach-deutschland\/\">Entsendung von Pflegekr\u00e4ften aus Drittstaaten nach Deutschland<\/a><\/strong><\/span><\/p>\n<h2 style=\"text-align: left;\">Definition des Begriffs \"entsandter Arbeitnehmer<\/h2>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Neben der Erl\u00e4uterung des Prozesses der Entsendung eines Arbeitnehmers sollte auch der Begriff des \"entsandten Arbeitnehmers\" gekl\u00e4rt werden. Ein entsandter Arbeitnehmer kann definiert werden als eine Person, die f\u00fcr einen begrenzten Zeitraum ihre Arbeit im Hoheitsgebiet eines anderen Mitgliedstaates als dem, in dem sie normalerweise arbeitet, verrichtet. Nat\u00fcrlich besteht die Aufgabe eines entsandten Arbeitnehmers darin, Arbeit f\u00fcr und unter der Kontrolle seines bisherigen Arbeitgebers zu verrichten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Lesen Sie auch: <strong><a href=\"https:\/\/bktkancelaria.pl\/de\/entsendung-von-auslandern-zur-arbeit-im-ausland\/\">Entsendung von Ausl\u00e4ndern zur Arbeit im Ausland<\/a><\/strong><\/p>\n<h2 style=\"text-align: left;\">Aushang einer Vereinbarung \u00fcber die Vermittlung von Mitarbeitern und Studenten<\/h2>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Was den Kern unserer Frage betrifft, so w\u00e4re es angebracht, dar\u00fcber nachzudenken und folgende Frage zu stellen: <strong>Gibt es eine Rechtsgrundlage f\u00fcr die Entsendung eines Arbeitnehmers, der im Rahmen eines Praktikumsvertrags f\u00fcr Hochschulabsolventen arbeitet?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">In diesem Fall lautet die Antwort leider nein.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Gem\u00e4\u00df der Richtlinie 96\/71\/EG der Europ\u00e4ischen Union ist es n\u00e4mlich m\u00f6glich, Arbeitnehmer zu entsenden, die w\u00e4hrend der Dauer der Entsendung weiterhin<\/span><span data-contrast=\"none\">mit dem Arbeitgeber <strong>in einem Arbeitsverh\u00e4ltnis oder <\/strong><\/span><strong>Bestellungen.\u00a0<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Im Gegensatz dazu kann ein Praktikantenvertrag nicht als Arbeitsvertrag oder Mandatsvertrag bezeichnet werden. In einem solchen Fall kann die Entsendung eines Auszubildenden und insbesondere eines Arbeitnehmers auf der Grundlage eines Praktikumsvertrags nicht als Grundlage f\u00fcr die ordnungsgem\u00e4\u00dfe Entsendung eines Arbeitnehmers angesehen werden.<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Zweck und Absicht der Praktikumsvereinbarung f\u00fcr Hochschulabsolventen ist:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span data-contrast=\"none\">den Erwerb von Erfahrungen durch den Arbeitnehmer und <\/span><\/li>\n<li><span data-contrast=\"none\">den Erwerb der f\u00fcr seinen Beruf erforderlichen praktischen F\u00e4higkeiten.\u00a0<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Die Entsendung einer Person, die im Rahmen eines solchen Vertrages als Auszubildender besch\u00e4ftigt ist, ist somit <strong>ist nicht m\u00f6glich.\u00a0<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<h2 style=\"text-align: left;\">Ausbildungsvertr\u00e4ge und Entsendung - k\u00f6nnen sie eine M\u00f6glichkeit sein, die Vorschriften zu umgehen? Die h\u00e4ufigsten Fehler bei der Entsendung von Arbeitnehmern<\/h2>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Es sei darauf hingewiesen, dass es eine besonders unkorrekte (und weit verbreitete) Praxis ist, einen Praktikumsvertrag f\u00fcr Hochschulabsolventen als Rechtsgrundlage f\u00fcr die Besch\u00e4ftigung eines Arbeitnehmers durch Unternehmen (sowie Zeitarbeitsfirmen) zu verwenden und<\/span><span data-contrast=\"none\"> Dienstleistungen mit Hilfe solcher \"Lehrlinge\" bei ihren Gesch\u00e4ftspartnern oder Unternehmen zu erbringen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Denn die Arbeitgeber gehen davon aus, dass sie durch die Entsendung eines \"Lehrlings\" zur Ausbildung ins Ausland viele unangenehme Formalit\u00e4ten vermeiden k\u00f6nnen. Zum Beispiel die Notwendigkeit, ein strenges Regime verbindlicher Vorschriften im Arbeitsland einzuhalten. Die fragliche Richtlinie erlegt denjenigen, die ihre Arbeitnehmer entsenden, genau eine solche Verpflichtung auf.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Nichts k\u00f6nnte jedoch weiter von der Wahrheit entfernt sein! Wir d\u00fcrfen nicht vergessen, dass die Entsendung von Arbeitnehmern einer strengen Kontrolle der Einhaltung der Vorschriften des Gastlandes unterliegt - sei es hinsichtlich der korrekten Einstellung, des Mindestlohns oder des Urlaubs - und zwar sowohl durch die Beh\u00f6rden des Gastlandes als auch des Entsendungslandes. Arbeitgeber, die ihre Arbeitnehmer im Rahmen eines Ausbildungsvertrags ins Ausland entsenden, setzen sich der Haftung f\u00fcr Verst\u00f6\u00dfe gegen Arbeitsrechte aus - und zwar in beiden L\u00e4ndern. Wir sollten hinzuf\u00fcgen, dass die staatliche Arbeitsaufsichtsbeh\u00f6rde derzeit von Unternehmen, die Arbeitnehmer aus Polen in andere EU-L\u00e4nder entsenden, Informationen anfordern kann - im Zusammenhang mit vermuteten Verst\u00f6\u00dfen gegen die Vorschriften des Gastlandes. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Es ist eine Umgehung des Gesetzes, wenn man mit den Arbeitnehmern Schulungsvereinbarungen abschlie\u00dft, ohne dass es \u00fcberhaupt einen Schulungsprozess gibt. Gleichzeitig riskiert man Geldstrafen in H\u00f6he von mehreren Tausend Dollar und setzt die Mitarbeiter selbst der Haftung aus. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"auto\">Wenn Sie daran interessiert sind, Ihren Personalbestand zu optimieren, wenden Sie sich an uns. Wir werden Sie unterst\u00fctzen, wir werden mitdenken, wir werden zuh\u00f6ren. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Polska jest niekwestionowanym liderem, je\u015bli chodzi o \u015bwiadczenie us\u0142ug transgranicznych. Zgodnie z danymi Komisji Europejskiej przedstawionymi we wniosku w sprawie dyrektywy wdro\u017ceniowej, w Unii Europejskiej pracuje ok. 1 miliona pracownik\u00f3w delegowanych, z tego 23% to Polacy. Na dalszych miejscach, czyli drugim oraz trzecim, z du\u017co ni\u017csz\u0105 liczb\u0105 tj. ok. 200 tys. pracownik\u00f3w znajduj\u0105 si\u0119 Francja [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[],"ppma_author":[237],"class_list":["post-6175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bez-kategorii"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umowy szkoleniowe a delegowanie - spos\u00f3b na omini\u0119cie przepis\u00f3w?<\/title>\n<meta name=\"description\" content=\"Czy umowy szkoleniowe mog\u0105 by\u0107 sposobem na \u0142atwiejsze delegowanie, poprzez omini\u0119cie przepis\u00f3w? Przeczytaj artyku\u0142 ekspertki i sprawd\u017a. &gt;&gt;&gt;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bktkancelaria.pl\/de\/ausbildungsvertrage-und-entsendung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umowy szkoleniowe a delegowanie - spos\u00f3b na omini\u0119cie przepis\u00f3w?\" \/>\n<meta property=\"og:description\" content=\"Czy umowy szkoleniowe mog\u0105 by\u0107 sposobem na \u0142atwiejsze delegowanie, poprzez omini\u0119cie przepis\u00f3w? Przeczytaj artyku\u0142 ekspertki i sprawd\u017a. &gt;&gt;&gt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bktkancelaria.pl\/de\/ausbildungsvertrage-und-entsendung\/\" \/>\n<meta property=\"og:site_name\" content=\"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bktkancelaria\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-09T07:15:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Beata Kielar-Tammert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beata Kielar-Tammert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/\"},\"author\":{\"name\":\"Beata Kielar-Tammert\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#\\\/schema\\\/person\\\/56b74e17111342a98fe1eb3b62aeb411\"},\"headline\":\"Umowy szkoleniowe a delegowanie &#8211; spos\u00f3b na omini\u0119cie przepis\u00f3w?\",\"datePublished\":\"2022-09-09T07:15:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/\"},\"wordCount\":932,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Umowy-szkoleniowe-a-delegowanie-1.png\",\"articleSection\":[\"Bez kategorii\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/\",\"name\":\"Umowy szkoleniowe a delegowanie - spos\u00f3b na omini\u0119cie przepis\u00f3w?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Umowy-szkoleniowe-a-delegowanie-1.png\",\"datePublished\":\"2022-09-09T07:15:53+00:00\",\"description\":\"Czy umowy szkoleniowe mog\u0105 by\u0107 sposobem na \u0142atwiejsze delegowanie, poprzez omini\u0119cie przepis\u00f3w? Przeczytaj artyku\u0142 ekspertki i sprawd\u017a. >>>\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Umowy-szkoleniowe-a-delegowanie-1.png\",\"contentUrl\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Umowy-szkoleniowe-a-delegowanie-1.png\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/umowy-szkoleniowe-a-delegowanie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/bktkancelaria.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umowy szkoleniowe a delegowanie &#8211; spos\u00f3b na omini\u0119cie przepis\u00f3w?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#website\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/\",\"name\":\"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych.\",\"description\":\"Profesjonalne doradztwo prawne od 1998 roku. \u0141\u0105czymy wieloletnie do\u015bwiadczenie z nowoczesnym podej\u015bciem do prawa mi\u0119dzynarodowego.\",\"publisher\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bktkancelaria.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#organization\",\"name\":\"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych.\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_.webp\",\"contentUrl\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_.webp\",\"width\":600,\"height\":172,\"caption\":\"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych.\"},\"image\":{\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bktkancelaria\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/beata-kielar-tammert\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bktkancelaria\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kancelariabkt.radcaprawnyb5036\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/#\\\/schema\\\/person\\\/56b74e17111342a98fe1eb3b62aeb411\",\"name\":\"Beata Kielar-Tammert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/fff-96x96.webpc6a54445d81855172bd1c10bba184f99\",\"url\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/fff-96x96.webp\",\"contentUrl\":\"https:\\\/\\\/bktkancelaria.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/fff-96x96.webp\",\"caption\":\"Beata Kielar-Tammert\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausbildungsvertr\u00e4ge und Abordnungen - eine M\u00f6glichkeit, die Vorschriften zu umgehen?","description":"K\u00f6nnten Ausbildungsvertr\u00e4ge eine M\u00f6glichkeit sein, die Entsendung durch Umgehung der Vorschriften zu erleichtern? Lesen Sie den Expertenartikel und pr\u00fcfen Sie. &gt;&gt;&gt;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bktkancelaria.pl\/de\/ausbildungsvertrage-und-entsendung\/","og_locale":"de_DE","og_type":"article","og_title":"Umowy szkoleniowe a delegowanie - spos\u00f3b na omini\u0119cie przepis\u00f3w?","og_description":"Czy umowy szkoleniowe mog\u0105 by\u0107 sposobem na \u0142atwiejsze delegowanie, poprzez omini\u0119cie przepis\u00f3w? Przeczytaj artyku\u0142 ekspertki i sprawd\u017a. >>>","og_url":"https:\/\/bktkancelaria.pl\/de\/ausbildungsvertrage-und-entsendung\/","og_site_name":"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych.","article_publisher":"https:\/\/www.facebook.com\/bktkancelaria","article_published_time":"2022-09-09T07:15:53+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie.png","type":"image\/png"}],"author":"Beata Kielar-Tammert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Beata Kielar-Tammert","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#article","isPartOf":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/"},"author":{"name":"Beata Kielar-Tammert","@id":"https:\/\/bktkancelaria.pl\/#\/schema\/person\/56b74e17111342a98fe1eb3b62aeb411"},"headline":"Umowy szkoleniowe a delegowanie &#8211; spos\u00f3b na omini\u0119cie przepis\u00f3w?","datePublished":"2022-09-09T07:15:53+00:00","mainEntityOfPage":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/"},"wordCount":932,"commentCount":0,"publisher":{"@id":"https:\/\/bktkancelaria.pl\/#organization"},"image":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#primaryimage"},"thumbnailUrl":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie-1.png","articleSection":["Bez kategorii"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/","url":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/","name":"Ausbildungsvertr\u00e4ge und Abordnungen - eine M\u00f6glichkeit, die Vorschriften zu umgehen?","isPartOf":{"@id":"https:\/\/bktkancelaria.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#primaryimage"},"image":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#primaryimage"},"thumbnailUrl":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie-1.png","datePublished":"2022-09-09T07:15:53+00:00","description":"K\u00f6nnten Ausbildungsvertr\u00e4ge eine M\u00f6glichkeit sein, die Entsendung durch Umgehung der Vorschriften zu erleichtern? Lesen Sie den Expertenartikel und pr\u00fcfen Sie. &gt;&gt;&gt;","breadcrumb":{"@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#primaryimage","url":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie-1.png","contentUrl":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2022\/09\/Umowy-szkoleniowe-a-delegowanie-1.png","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/bktkancelaria.pl\/umowy-szkoleniowe-a-delegowanie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/bktkancelaria.pl\/"},{"@type":"ListItem","position":2,"name":"Umowy szkoleniowe a delegowanie &#8211; spos\u00f3b na omini\u0119cie przepis\u00f3w?"}]},{"@type":"WebSite","@id":"https:\/\/bktkancelaria.pl\/#website","url":"https:\/\/bktkancelaria.pl\/","name":"International Law Office - Professionelle rechtliche Unterst\u00fctzung in internationalen Angelegenheiten.","description":"Professionelle Rechtsberatung seit 1998. Wir verbinden langj\u00e4hrige Erfahrung mit einem modernen Ansatz im internationalen Recht.","publisher":{"@id":"https:\/\/bktkancelaria.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bktkancelaria.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bktkancelaria.pl\/#organization","name":"International Law Office - Professionelle rechtliche Unterst\u00fctzung in internationalen Angelegenheiten.","url":"https:\/\/bktkancelaria.pl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bktkancelaria.pl\/#\/schema\/logo\/image\/","url":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/04\/Logo_.webp","contentUrl":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/04\/Logo_.webp","width":600,"height":172,"caption":"Kancelaria Prawa Mi\u0119dzynarodowego - Profesjonalne wsparcie prawne w sprawach mi\u0119dzynarodowych."},"image":{"@id":"https:\/\/bktkancelaria.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bktkancelaria","https:\/\/www.linkedin.com\/in\/beata-kielar-tammert\/","https:\/\/www.instagram.com\/bktkancelaria\/","https:\/\/www.youtube.com\/@kancelariabkt.radcaprawnyb5036"]},{"@type":"Person","@id":"https:\/\/bktkancelaria.pl\/#\/schema\/person\/56b74e17111342a98fe1eb3b62aeb411","name":"Beata Kielar-Tammert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/01\/fff-96x96.webpc6a54445d81855172bd1c10bba184f99","url":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/01\/fff-96x96.webp","contentUrl":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/01\/fff-96x96.webp","caption":"Beata Kielar-Tammert"}}]}},"authors":[{"term_id":237,"user_id":1,"is_guest":0,"slug":"admin","display_name":"Beata Kielar-Tammert","avatar_url":"https:\/\/bktkancelaria.pl\/wp-content\/uploads\/2023\/01\/fff-96x96.webp","author_category":"","first_name":"Beata","last_name":"Kielar-Tammert","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/posts\/6175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/comments?post=6175"}],"version-history":[{"count":0,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/posts\/6175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/media\/6180"}],"wp:attachment":[{"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/media?parent=6175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/categories?post=6175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/tags?post=6175"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/bktkancelaria.pl\/de\/wp-json\/wp\/v2\/ppma_author?post=6175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}